{"id":3699,"date":"2023-12-21T11:40:13","date_gmt":"2023-12-21T10:40:13","guid":{"rendered":"https:\/\/matris.eu\/terminos-y-condiciones-generales\/"},"modified":"2025-06-23T15:50:51","modified_gmt":"2025-06-23T13:50:51","slug":"terminos-y-condiciones-generales","status":"publish","type":"page","link":"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/","title":{"rendered":"T\u00e9rminos y condiciones generales"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=\u00bb0&#8243; override_padding=\u00bbyes\u00bb h_padding=\u00bb2&#8243; top_padding=\u00bb3&#8243; bottom_padding=\u00bb3&#8243; back_color=\u00bbcolor-193339&#8243; overlay_alpha=\u00bb50&#8243; gutter_size=\u00bb3&#8243; column_width_percent=\u00bb100&#8243; shift_y=\u00bb0&#8243; z_index=\u00bb0&#8243; uncode_shortcode_id=\u00bb201722&#8243; back_color_type=\u00bbuncode-palette\u00bb][vc_column column_width_percent=\u00bb100&#8243; align_horizontal=\u00bbalign_center\u00bb gutter_size=\u00bb3&#8243; overlay_alpha=\u00bb50&#8243; shift_x=\u00bb0&#8243; shift_y=\u00bb0&#8243; shift_y_down=\u00bb0&#8243; z_index=\u00bb0&#8243; medium_width=\u00bb0&#8243; mobile_width=\u00bb0&#8243; width=\u00bb1\/1&#8243; uncode_shortcode_id=\u00bb174409&#8243;][vc_custom_heading heading_semantic=\u00bbh1&#8243; text_size=\u00bbh1&#8243; separator_color=\u00bbyes\u00bb separator=\u00bbunder\u00bb sub_lead=\u00bbyes\u00bb sub_reduced=\u00bbyes\u00bb uncode_shortcode_id=\u00bb167187&#8243; subheading=\u00bbCondiciones generales de servicio para motores el\u00e9ctricos, servomotores, motores de husillo y otros componentes\u00bb]T\u00e9rminos y condiciones generales[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row row_height_percent=\u00bb0&#8243; override_padding=\u00bbyes\u00bb h_padding=\u00bb2&#8243; top_padding=\u00bb3&#8243; bottom_padding=\u00bb3&#8243; overlay_alpha=\u00bb50&#8243; gutter_size=\u00bb3&#8243; column_width_percent=\u00bb100&#8243; shift_y=\u00bb0&#8243; z_index=\u00bb0&#8243; uncode_shortcode_id=\u00bb110540&#8243;][vc_column width=\u00bb1\/1&#8243;][vc_column_text uncode_shortcode_id=\u00bb197631&#8243;]<\/p>\n<h3>1. Contrato y restricciones<\/h3>\n<p>Estos t\u00e9rminos y condiciones forman parte del contrato celebrado con cada proyecto entre Matris y el cliente con el fin de realizar el servicio de los motores el\u00e9ctricos, servomotores y motores de husillo del cliente entregados a Matris para su servicio o reparaci\u00f3n.<\/p>\n<p>Matris d.o.o. no est\u00e1 obligado por ning\u00fan t\u00e9rmino adicional o de otro tipo, ya sea en forma impresa o en cualquier otra forma, ya sea en un formulario de pedido del cliente o en cualquier otra comunicaci\u00f3n entre el cliente y Matris, a menos que Matris acepte esto expresamente por escrito.<\/p>\n<p>El contrato se celebra exclusivamente entre Matris y el cliente y exclusivamente para beneficio de las partes contratantes. Ning\u00fan tercero ni ninguna otra persona que no sea parte del contrato podr\u00e1 exigir su cumplimiento ni ninguna otra disposici\u00f3n del mismo. La disposici\u00f3n mencionada excluye expresamente los derechos de un tercero si este est\u00e1 representado por un intermediario que celebra un contrato con Matris.  <\/p>\n<p>Los contactos comerciales previos, las pr\u00e1cticas comerciales y los acuerdos verbales que no est\u00e9n escritos y firmados por Matris en la parte que constituir\u00eda un cambio al contrato no son vinculantes para Matris.<\/p>\n<p>El contrato se considera concluido cuando: (a) el cliente ha emitido una orden de compra oficial a Matris, o (b) el cliente ha pagado a Matris el importe total especificado en las condiciones de pago en la oferta o factura anticipada, o (c) el cliente ha confirmado la reparaci\u00f3n por escrito a trav\u00e9s del buz\u00f3n de correo electr\u00f3nico que figura en el sitio web del cliente, lo utiliza regularmente en la comunicaci\u00f3n con Matris, o se demuestra claramente que es el correo electr\u00f3nico oficial del cliente o de un empleado empleado por \u00e9l, o (d) el cliente ha confirmado la reparaci\u00f3n\/servicio con una confirmaci\u00f3n escrita firmada y sellada.    <\/p>\n<p>En caso de que el cliente no se decida por una reparaci\u00f3n, servicio u otro servicio y desista de la oferta, elaborada a partir de la inspecci\u00f3n, el diagn\u00f3stico y el desmontaje recibidos, a pesar de no haber recibido confirmaci\u00f3n, se le cobrar\u00e1 una parte proporcional del tiempo empleado en la preparaci\u00f3n de la oferta. El coste se comunicar\u00e1 tras la denegaci\u00f3n, cuando quede claro que el servicio no se confirmar\u00e1. De lo contrario, la parte cobrada formar\u00e1 parte del paquete de servicios est\u00e1ndar.[\/vc_column_text][vc_separator sep_color=\u00bbcolor-uydo\u00bb uncode_shortcode_id=\u00bb741629&#8243; sep_color_type=\u00bbuncode-palette\u00bb][vc_column_text uncode_shortcode_id=\u00bb180480&#8243;]<\/p>\n<h3>2. Terminaci\u00f3n<\/h3>\n<p>El cliente podr\u00e1 rescindir el contrato celebrado con un preaviso de tres meses y siempre que, a primera solicitud de Matris, liquide todas las obligaciones y costes pendientes en los que Matris haya incurrido o haya incurrido como consecuencia de la ejecuci\u00f3n del contrato. En el caso de contratos puntuales, el cliente solo podr\u00e1 rescindirlo si lo notifica dentro de los 5 d\u00edas siguientes a su celebraci\u00f3n. En este caso, el cliente tambi\u00e9n estar\u00e1 obligado a cubrir todos los costes en los que Matris haya incurrido en relaci\u00f3n con la ejecuci\u00f3n del contrato. En caso de rescisi\u00f3n del contrato, el cliente ser\u00e1 responsable de todos los costes administrativos y de la devoluci\u00f3n del objeto del contrato. Si, como consecuencia de la ejecuci\u00f3n del contrato y antes de recibir la rescisi\u00f3n, Matris hubiera suministrado piezas de repuesto para la ejecuci\u00f3n del contrato rescindido, el cliente estar\u00e1 obligado a adquirirlas al precio de compra y a reembolsar todos los dem\u00e1s costes.    <\/p>\n<p>La cancelaci\u00f3n del contrato deber\u00e1 realizarse por escrito (por correo electr\u00f3nico o correo postal) y comunicarse a Matris de tal forma que se asegure la recepci\u00f3n de la cancelaci\u00f3n y la prueba de la misma.<\/p>\n<p>Matris podr\u00e1 rescindir el Acuerdo mediante notificaci\u00f3n por escrito al Cliente, siempre que Matris entregue inmediatamente la propiedad del Cliente al servicio de entrega apropiado para su devoluci\u00f3n al Cliente sin coste alguno para \u00e9ste.[\/vc_column_text][vc_separator sep_color=\u00bbcolor-uydo\u00bb uncode_shortcode_id=\u00bb741629&#8243; sep_color_type=\u00bbuncode-palette\u00bb][vc_column_text uncode_shortcode_id=\u00bb769835&#8243;]<\/p>\n<h3>3. Precio y pago<\/h3>\n<p>El cliente corre con todos los gastos de env\u00edo, excepto la parte que Matris asuma expresamente de conformidad con el contrato celebrado y las presentes condiciones generales.<\/p>\n<p>Los gastos de transporte forman parte de la oferta, que el cliente confirma al realizar el pago. Las condiciones de pago dependen del acuerdo individual con el cliente o se indican en la oferta\/factura proforma. Matris cobra un 30 % adicional sobre el precio del servicio b\u00e1sico en casos excepcionales: (a) que no est\u00e9n incluidos en el plan de servicios habitual de Matris, (b) que se realicen por la tarde fuera del horario de oficina, (c) que se realicen durante fines de semana y festivos, o (d) que se trate de un servicio urgente. Matris podr\u00e1 solicitar un prepago total o parcial, o una garant\u00eda de pago a un tercero por adelantado, en el caso de la primera transacci\u00f3n realizada con un nuevo cliente, antes de la prestaci\u00f3n de los servicios o entregas, o cuando Matris lo considere prudente.       <\/p>\n<p>Si el cliente no paga a Matris dentro del plazo legalmente requerido y si se contrata a un abogado para cobrar la factura impaga del cliente, el cliente debe pagar todos los honorarios de abogados y expertos en los que incurra Matris.[\/vc_column_text][vc_separator sep_color=\u00bbcolor-uydo\u00bb uncode_shortcode_id=\u00bb741629&#8243; sep_color_type=\u00bbuncode-palette\u00bb][vc_column_text uncode_shortcode_id=\u00bb753181&#8243;]<\/p>\n<h3>4. Entrega<\/h3>\n<p>Matris no puede garantizar los plazos de entrega, pero los establece bas\u00e1ndose en una evaluaci\u00f3n de buena fe y asumiendo que toda la informaci\u00f3n recibida del cliente es completa y que no habr\u00e1 retrasos causados \u200b\u200bo contribuidos por circunstancias fuera del control razonable de Matris.<\/p>\n<p>Matris no ser\u00e1 responsable de ning\u00fan retraso en la ejecuci\u00f3n o incumplimiento del contrato que se deba parcial o totalmente a la influencia directa o indirecta de fuerza mayor, imposibilidad de obtener repuestos o componentes, huelgas, guerras, insurrecciones, emergencias nacionales o locales, decretos gubernamentales, interrupciones en el transporte, actos u omisiones del cliente o circunstancias similares fuera del control razonable de Matris.<\/p>\n<p>Matris garantiza al cliente los precios de los recambios seg\u00fan las listas regulares de precios de venta al p\u00fablico de los proveedores, v\u00e1lidas en el momento de la transacci\u00f3n concluida.[\/vc_column_text][vc_separator sep_color=\u00bbcolor-uydo\u00bb uncode_shortcode_id=\u00bb741629&#8243; sep_color_type=\u00bbuncode-palette\u00bb][vc_column_text uncode_shortcode_id=\u00bb204757&#8243;]<\/p>\n<h3>5. Riesgo de p\u00e9rdida\/bienes no reclamados del cliente<\/h3>\n<p>El Cliente asume todos los riesgos de p\u00e9rdida de sus bienes mientras est\u00e9n en manos o bajo el control del servicio de entrega. El Cliente garantiza a Matris que sus bienes estar\u00e1n siempre asegurados contra cualquier da\u00f1o que puedan causar. <\/p>\n<p>Si la Propiedad del Cliente entregada a Matris no se repara por no haber autorizado la reparaci\u00f3n y permanece en las instalaciones de servicio de Matris durante sesenta (60) d\u00edas o m\u00e1s despu\u00e9s de que Matris haya solicitado la autorizaci\u00f3n de reparaci\u00f3n, se considerar\u00e1 que el Cliente ha transferido expresa e irrevocablemente la propiedad de la Propiedad entregada a Matris como pago por su custodia. El Cliente se considerar\u00e1 en mora desde el momento en que Matris solicite la autorizaci\u00f3n de reparaci\u00f3n hasta que esta se autorice o se transfiera la propiedad a Matris, y ser\u00e1 responsable de todos los da\u00f1os a la Propiedad y de cualquier p\u00e9rdida o da\u00f1o que Matris sufra como resultado de la falta de autorizaci\u00f3n de reparaci\u00f3n.[\/vc_column_text][vc_separator sep_color=\u00bbcolor-uydo\u00bb uncode_shortcode_id=\u00bb741629&#8243; sep_color_type=\u00bbuncode-palette\u00bb][vc_column_text uncode_shortcode_id=\u00bb145031&#8243;]<\/p>\n<h3>6. Garant\u00eda limitada<\/h3>\n<p>En lugar de cualquier otra garant\u00eda, expresa o impl\u00edcita, incluyendo, pero no limitado a, todas las garant\u00edas de comerciabilidad y\/o idoneidad para un prop\u00f3sito particular, Matris por la presente emite esta garant\u00eda limitada para motores el\u00e9ctricos, servomotores y motores de husillo reparados por Matris bajo contrato, \u00fanicamente a la parte a nombre de la cual se emite la factura (y no a cualquier propietario posterior del equipo reparado ni a cualquier otra persona o entidad): Matris garantiza que cada componente reparado (motor el\u00e9ctrico, servomotor, motor de husillo, reductor, bomba y similares) cuando sale de las instalaciones de servicio de Matris se ajustar\u00e1 a las especificaciones del fabricante original y garantiza que cada componente reparado estar\u00e1 libre de defectos resultantes del servicio durante el per\u00edodo de garant\u00eda a partir de la fecha de reparaci\u00f3n. Matris garantiza que el servicio o la reparaci\u00f3n se realizar\u00e1 profesional y correctamente, pero Matris renuncia expresamente a cualquier responsabilidad por la calidad de la mano de obra, los materiales y las piezas de repuesto utilizadas para realizar la reparaci\u00f3n\/servicio.[\/vc_column_text][vc_column_text uncode_shortcode_id=\u00bb682984&#8243;]<\/p>\n<h3>6a.  <strong>Garant\u00eda de 24 meses<\/strong><\/h3>\n<p>Solo es posible opcionalmente, con un recargo proporcional. La garant\u00eda se otorga \u00fanicamente por los servicios prestados en el centro de servicio Matris. Los componentes electr\u00f3nicos, repuestos o piezas de repuesto adquiridos no est\u00e1n cubiertos por la garant\u00eda.  <\/p>\n<p>El cliente deber\u00e1 hacer valer cualquier derecho de garant\u00eda seg\u00fan el procedimiento establecido en estos t\u00e9rminos y condiciones y teniendo en cuenta los supuestos que se enumeran a continuaci\u00f3n, de lo contrario perder\u00e1 este derecho.<\/p>\n<p>En caso de que el cliente presente una solicitud oportuna y justificada para la correcci\u00f3n del defecto, Matris decidir\u00e1 exclusivamente si reparar\u00e1 el componente que (a) no es conforme o (b) funciona mal o (c) no funciona, o reembolsar\u00e1 al cliente los costos de reparaci\u00f3n.   <\/p>\n<p>EN NING\u00daN CASO MATRIS SER\u00c1 RESPONSABLE POR PROBLEMAS O MAL FUNCIONAMIENTO DEL MOTOR EL\u00c9CTRICO, SERVOMOTOR O MOTOR DE HUSILLO O CUALQUIER OTRA MAQUINARIA, EQUIPO, APLICACI\u00d3N O PROCESO DEL CUAL UN MOTOR EL\u00c9CTRICO, SERVOMOTOR, MOTOR DE HUSILLO O CUALQUIER OTRO COMPONENTE ES PARTE O COMPONENTE, Y EN NING\u00daN CASO MATRIS SER\u00c1 RESPONSABLE POR CUALQUIER DA\u00d1O (INDIRECTO O CONSECUENTE) QUE SURJA DEL USO DEL MOTOR EL\u00c9CTRICO, SERVOMOTOR O MOTOR DE HUSILLO O CUALQUIER OTRO COMPONENTE, O LA FALLA DE UN MOTOR EL\u00c9CTRICO, SERVOMOTOR O MOTOR DE HUSILLO O CUALQUIER OTRO COMPONENTE REPARADO, BAJO ESTA GARANT\u00cdA LIMITADA. NO OBSTANTE TODO LO ANTERIOR, LA RESPONSABILIDAD DE MATRIS SE LIMITA AL IMPORTE DE LA FACTURA EMITIDA AL CLIENTE Y PAGADA POR ESTE POR LOS SERVICIOS PRESTADOS. EN LA MEDIDA EN QUE EL CLIENTE NO HAYA CUMPLIDO CON SUS OBLIGACIONES O LAS HAYA CUMPLIDO SOLO PARCIALMENTE, MATRIS TIENE EL DERECHO A RETIRAR SU DECISI\u00d3N SOBRE LA RECLAMACI\u00d3N HASTA QUE SE HAYA ABONADO TOTALMENTE LA FACTURA EMITIDA.  <\/p>\n<p>Matris no ser\u00e1 responsable ante el cliente ni ante ninguna otra persona por ning\u00fan da\u00f1o directo o indirecto si el cliente o cualquier otra persona: (a) modifica, manipula o intenta reparar un motor el\u00e9ctrico, servomotor, motor de husillo o cualquier otro componente despu\u00e9s de que haya sido reparado por Matris, o (b) utiliza un motor el\u00e9ctrico, servomotor, motor de husillo o cualquier otro componente de una manera distinta a la recomendada por el fabricante, o (c) utiliza un motor el\u00e9ctrico, servomotor, motor de husillo o cualquier otro componente en cualquier m\u00e1quina, equipo, aplicaci\u00f3n o proceso para el cual el fabricante del motor el\u00e9ctrico, servomotor, motor de husillo o cualquier otro componente no lo haya aprobado, o (d) si la falla en el reclamo del motor el\u00e9ctrico, servomotor, motor de husillo o cualquier otro componente reparado es el resultado de un uso indebido, falta de mantenimiento, abuso, accidente o falla de otra m\u00e1quina o equipo o su componente, o (e) si el cliente ha entregado un motor el\u00e9ctrico, servomotor o motor de husillo ya desmontado o incompleto a Matris para su reparaci\u00f3n.     <\/p>\n<p>Si el motor el\u00e9ctrico, servomotor, motor de husillo u otro componente del Cliente est\u00e1 cubierto por cualquier garant\u00eda del fabricante a la fecha en que el Cliente realiza un reclamo de garant\u00eda, el Cliente acepta realizar dicho reclamo bajo la garant\u00eda del fabricante y acepta que la garant\u00eda del fabricante prevalecer\u00e1 sobre la garant\u00eda limitada de Matris, que no se aplicar\u00e1 en tal caso; sin embargo, Matris puede realizar servicios de reparaci\u00f3n para el motor el\u00e9ctrico, servomotor o motor de husillo del Cliente a su entera discreci\u00f3n, pero solo si lo autoriza por escrito el fabricante.[\/vc_column_text][vc_row_inner row_inner_height_percent=\u00bb0&#8243; overlay_alpha=\u00bb50&#8243; gutter_size=\u00bb3&#8243; border_color=\u00bbcolor-uydo\u00bb border_style=\u00bbsolid\u00bb shift_y=\u00bb0&#8243; z_index=\u00bb0&#8243; uncode_shortcode_id=\u00bb139459&#8243; css=\u00bb.vc_custom_1703154773629{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;}\u00bb border_color_type=\u00bbuncode-palette\u00bb][vc_column_inner column_width_percent=\u00bb100&#8243; gutter_size=\u00bb3&#8243; override_padding=\u00bbyes\u00bb column_padding=\u00bb2&#8243; overlay_alpha=\u00bb50&#8243; shift_x=\u00bb0&#8243; shift_y=\u00bb0&#8243; shift_y_down=\u00bb0&#8243; z_index=\u00bb0&#8243; medium_width=\u00bb0&#8243; mobile_width=\u00bb0&#8243; width=\u00bb1\/1&#8243; uncode_shortcode_id=\u00bb130938&#8243;][vc_column_text uncode_shortcode_id=\u00bb678010&#8243;]<\/p>\n<h3>PROCEDIMIENTO DE GARANT\u00cdA<\/h3>\n<p>Si el Cliente alega que un equipo reparado por Matris no cumpl\u00eda con las especificaciones originales del fabricante al recibirlo, o si alega que se produjo un defecto durante el per\u00edodo de garant\u00eda, deber\u00e1 notificarlo por escrito a Matris de inmediato, y en ning\u00fan caso despu\u00e9s del vencimiento de dicho per\u00edodo. El Cliente ser\u00e1 responsable de todos los gastos de env\u00edo, manipulaci\u00f3n y similares derivados de la devoluci\u00f3n del motor reparado a Matris. Al recibir el motor, el personal de servicio de Matris lo inspeccionar\u00e1 para determinar si la falta de conformidad o el defecto (seg\u00fan corresponda) alegado en la reclamaci\u00f3n est\u00e1 relacionado con la reparaci\u00f3n realizada por Matris.  <\/p>\n<p>Si Matris determina que la falta de conformidad o el defecto no est\u00e1 relacionado con un servicio anterior de Matris o que la reclamaci\u00f3n del Cliente se debe a una o m\u00e1s de las condiciones descritas en los p\u00e1rrafos 3(a) a (d) anteriores, Matris notificar\u00e1 de inmediato al Cliente y solicitar\u00e1 su aprobaci\u00f3n para realizar reparaciones adicionales al precio vigente en ese momento. Matris no realizar\u00e1 ninguna reparaci\u00f3n adicional sin la aprobaci\u00f3n previa por escrito del Cliente. <\/p>\n<p>Si, dentro de los diez (10) d\u00edas posteriores a la solicitud de Matris para la aprobaci\u00f3n de la reparaci\u00f3n, el cliente solicita la devoluci\u00f3n del motor sin reparar, Matris lo devolver\u00e1 a cargo del cliente y cobrar\u00e1 una tarifa de diagn\u00f3stico prorrateada seg\u00fan el tipo y tama\u00f1o del motor. Si el cliente no autoriza reparaciones adicionales ni solicita la devoluci\u00f3n del motor dentro de los diez (10) d\u00edas, deber\u00e1 pagar a Matris el almacenamiento diario del motor, seg\u00fan la tarifa establecida por Matris (Matris proporcionar\u00e1 las tarifas vigentes a solicitud del cliente). Si el motor permanece en el almac\u00e9n de Matris durante sesenta (60) d\u00edas o m\u00e1s despu\u00e9s de que Matris haya solicitado la aprobaci\u00f3n de la reparaci\u00f3n, se considerar\u00e1 abandonado por el cliente y Matris podr\u00e1 disponer de \u00e9l a su entera discreci\u00f3n sin incurrir en ninguna responsabilidad hacia el cliente.  <\/p>\n<p>Si Matris determina que la no conformidad o el defecto est\u00e1 cubierto por los t\u00e9rminos y condiciones de la garant\u00eda limitada y si Matris elige reparar el motor bajo la garant\u00eda limitada, Matris no le cobrar\u00e1 al cliente por el servicio de reparaci\u00f3n y el motor ser\u00e1 devuelto al cliente a trav\u00e9s del servicio de entrega a cargo de Matris.<\/p>\n<p><strong>LA GARANT\u00cdA LIMITADA DESCRITA ANTERIORMENTE ES EXCLUSIVA Y SUSTITUYE A TODAS LAS DEM\u00c1S GARANT\u00cdAS, EXPRESAS O IMPL\u00cdCITAS, INCLUIDAS, ENTRE OTRAS, TODAS LAS GARANT\u00cdAS DE COMERCIABILIDAD O IDONEIDAD PARA UN PROP\u00d3SITO PARTICULAR.<\/strong>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text uncode_shortcode_id=\u00bb192849&#8243;]<\/p>\n<h3>7. Declaraciones del cliente, limitaci\u00f3n de responsabilidad de Matris, indemnizaci\u00f3n<\/h3>\n<p>El Cliente garantiza a Matris que es el propietario o tiene derecho a poseer y disponer de su propiedad. Si alguna parte de la propiedad del Cliente es un componente que ha sido o ha sido modificado con respecto a las especificaciones, configuraci\u00f3n o est\u00e1ndares de rendimiento originales del fabricante, Matris no ser\u00e1 responsable ante el Cliente ni ante terceros por los resultados o consecuencias, directos o indirectos, de los servicios prestados por Matris en dicha parte de la propiedad del Cliente.[\/vc_column_text][vc_column_text uncode_shortcode_id=\u00bb192630&#8243;]<\/p>\n<h3>7a.  <strong>Procesamiento de componentes<\/strong><\/h3>\n<p>Nos reservamos el derecho de implementar detalles t\u00e9cnicos o implementaciones (tanto de software como de hardware) que no afecten la funcionalidad del objeto de la oferta a nuestra propia discreci\u00f3n profesional. <\/p>\n<p>El Cliente deber\u00e1 indemnizar y eximir de responsabilidad a Matris, sus directores, funcionarios, agentes y empleados, frente a cualquier reclamaci\u00f3n, garant\u00eda, indemnizaci\u00f3n, demanda, sentencia, multa, sanci\u00f3n, evaluaci\u00f3n, da\u00f1o, coste y gasto, incluidos los honorarios de abogados, en la defensa contra lo anterior o en la reivindicaci\u00f3n del derecho a indemnizaci\u00f3n por da\u00f1os y perjuicios, derivados de lesiones o fallecimiento de cualquier persona o da\u00f1os materiales, incluidos, entre otros, los bienes del Cliente, derivados de (a) cualquier acto u omisi\u00f3n del Cliente, (b) cualquier declaraci\u00f3n falsa del Cliente, o (c) la prestaci\u00f3n de servicios por parte de Matris al Cliente en cualquier componente cuyas especificaciones, configuraci\u00f3n o est\u00e1ndares de rendimiento del fabricante original se hayan alterado o modificado. Las disposiciones de esta Secci\u00f3n permanecer\u00e1n vigentes tras la rescisi\u00f3n o ejecuci\u00f3n de este Acuerdo.[\/vc_column_text][vc_separator sep_color=\u00bbcolor-uydo\u00bb uncode_shortcode_id=\u00bb741629&#8243; sep_color_type=\u00bbuncode-palette\u00bb][vc_column_text uncode_shortcode_id=\u00bb162150&#8243;]<\/p>\n<h3>8. Ley aplicable<\/h3>\n<p>El lugar de celebraci\u00f3n y ejecuci\u00f3n del contrato ser\u00e1 Kranj. El contrato se regir\u00e1 por las leyes de la Rep\u00fablica de Eslovenia. Toda reclamaci\u00f3n por presunto incumplimiento de este contrato o de cualquier acuerdo o garant\u00eda de Matris deber\u00e1 presentarse ante el Tribunal de Distrito de Kranj. En caso de litigio, se aplicar\u00e1 la legislaci\u00f3n eslovena.[\/vc_column_text][vc_separator sep_color=\u00bbcolor-uydo\u00bb uncode_shortcode_id=\u00bb741629&#8243; sep_color_type=\u00bbuncode-palette\u00bb][vc_column_text uncode_shortcode_id=\u00bb584886&#8243;]<\/p>\n<h3>9. Varios<\/h3>\n<p>Si un tribunal competente declara nula alguna disposici\u00f3n del contrato o de estos t\u00e9rminos y condiciones, se considerar\u00e1 que el contrato en s\u00ed no es nulo por la nulidad de alguna disposici\u00f3n contractual, si pudiera existir sin la disposici\u00f3n nula y si dicha disposici\u00f3n no fue una condici\u00f3n contractual ni un motivo decisivo para la celebraci\u00f3n del contrato. El contrato y sus anexos constituyen el contrato completo entre el cliente y Matris.[\/vc_column_text][vc_separator sep_color=\u00bbcolor-uydo\u00bb uncode_shortcode_id=\u00bb741629&#8243; sep_color_type=\u00bbuncode-palette\u00bb][vc_column_text uncode_shortcode_id=\u00bb146592&#8243;]Matris d.o.o., febrero de 2024[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_height_percent=\u00bb0&#8243; override_padding=\u00bbyes\u00bb h_padding=\u00bb2&#8243; top_padding=\u00bb3&#8243; bottom_padding=\u00bb3&#8243; back_color=\u00bbcolor-193339&#8243; overlay_alpha=\u00bb50&#8243; gutter_size=\u00bb3&#8243; column_width_percent=\u00bb100&#8243; shift_y=\u00bb0&#8243; z_index=\u00bb0&#8243; uncode_shortcode_id=\u00bb201722&#8243; back_color_type=\u00bbuncode-palette\u00bb][vc_column column_width_percent=\u00bb100&#8243; align_horizontal=\u00bbalign_center\u00bb gutter_size=\u00bb3&#8243; overlay_alpha=\u00bb50&#8243; shift_x=\u00bb0&#8243; shift_y=\u00bb0&#8243; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":12,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3699","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9rminos y condiciones generales | Matris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y condiciones generales | Matris\" \/>\n<meta property=\"og:description\" content=\"[vc_row row_height_percent=\u00bb0&#8243; override_padding=\u00bbyes\u00bb h_padding=\u00bb2&#8243; top_padding=\u00bb3&#8243; bottom_padding=\u00bb3&#8243; back_color=\u00bbcolor-193339&#8243; overlay_alpha=\u00bb50&#8243; gutter_size=\u00bb3&#8243; column_width_percent=\u00bb100&#8243; shift_y=\u00bb0&#8243; z_index=\u00bb0&#8243; uncode_shortcode_id=\u00bb201722&#8243; back_color_type=\u00bbuncode-palette\u00bb][vc_column column_width_percent=\u00bb100&#8243; align_horizontal=\u00bbalign_center\u00bb gutter_size=\u00bb3&#8243; overlay_alpha=\u00bb50&#8243; shift_x=\u00bb0&#8243; shift_y=\u00bb0&#8243; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/\" \/>\n<meta property=\"og:site_name\" content=\"Matris\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Matrisdoo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-23T13:50:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/matris.eu\/wp-content\/uploads\/2024\/02\/matris_seo_image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/terminos-y-condiciones-generales\\\/\",\"url\":\"https:\\\/\\\/matris.eu\\\/es\\\/terminos-y-condiciones-generales\\\/\",\"name\":\"T\u00e9rminos y condiciones generales | Matris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#website\"},\"datePublished\":\"2023-12-21T10:40:13+00:00\",\"dateModified\":\"2025-06-23T13:50:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/terminos-y-condiciones-generales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/matris.eu\\\/es\\\/terminos-y-condiciones-generales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/terminos-y-condiciones-generales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/matris.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos y condiciones generales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/matris.eu\\\/es\\\/\",\"name\":\"Servisni center Matris\",\"description\":\"Servis elektro, servo in vretenskih motorjev\",\"publisher\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#organization\"},\"alternateName\":\"Matris\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/matris.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#organization\",\"name\":\"Centro de servicio Matris\",\"alternateName\":\"Matris\",\"url\":\"https:\\\/\\\/matris.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Centro de servicio Matris\"},\"image\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Matrisdoo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/matris_doo\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y condiciones generales | Matris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9rminos y condiciones generales | Matris","og_description":"[vc_row row_height_percent=\u00bb0&#8243; override_padding=\u00bbyes\u00bb h_padding=\u00bb2&#8243; top_padding=\u00bb3&#8243; bottom_padding=\u00bb3&#8243; back_color=\u00bbcolor-193339&#8243; overlay_alpha=\u00bb50&#8243; gutter_size=\u00bb3&#8243; column_width_percent=\u00bb100&#8243; shift_y=\u00bb0&#8243; z_index=\u00bb0&#8243; uncode_shortcode_id=\u00bb201722&#8243; back_color_type=\u00bbuncode-palette\u00bb][vc_column column_width_percent=\u00bb100&#8243; align_horizontal=\u00bbalign_center\u00bb gutter_size=\u00bb3&#8243; overlay_alpha=\u00bb50&#8243; shift_x=\u00bb0&#8243; shift_y=\u00bb0&#8243; [&hellip;]","og_url":"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/","og_site_name":"Matris","article_publisher":"https:\/\/www.facebook.com\/Matrisdoo","article_modified_time":"2025-06-23T13:50:51+00:00","og_image":[{"width":1200,"height":1000,"url":"https:\/\/matris.eu\/wp-content\/uploads\/2024\/02\/matris_seo_image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/","url":"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/","name":"T\u00e9rminos y condiciones generales | Matris","isPartOf":{"@id":"https:\/\/matris.eu\/es\/#website"},"datePublished":"2023-12-21T10:40:13+00:00","dateModified":"2025-06-23T13:50:51+00:00","breadcrumb":{"@id":"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/matris.eu\/es\/terminos-y-condiciones-generales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/matris.eu\/es\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y condiciones generales"}]},{"@type":"WebSite","@id":"https:\/\/matris.eu\/es\/#website","url":"https:\/\/matris.eu\/es\/","name":"Servisni center Matris","description":"Servis elektro, servo in vretenskih motorjev","publisher":{"@id":"https:\/\/matris.eu\/es\/#organization"},"alternateName":"Matris","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/matris.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/matris.eu\/es\/#organization","name":"Centro de servicio Matris","alternateName":"Matris","url":"https:\/\/matris.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/matris.eu\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Centro de servicio Matris"},"image":{"@id":"https:\/\/matris.eu\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Matrisdoo","https:\/\/www.linkedin.com\/company\/matris_doo\/"]}]}},"_links":{"self":[{"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/pages\/3699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/comments?post=3699"}],"version-history":[{"count":4,"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/pages\/3699\/revisions"}],"predecessor-version":[{"id":3998,"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/pages\/3699\/revisions\/3998"}],"wp:attachment":[{"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/media?parent=3699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}