{"id":45,"count":3,"description":"","link":"https:\/\/matris.eu\/es\/category\/noticias\/","name":"Noticias","slug":"noticias","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noticias Archives | Matris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/matris.eu\/es\/category\/noticias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noticias Archives | Matris\" \/>\n<meta property=\"og:url\" content=\"https:\/\/matris.eu\/es\/category\/noticias\/\" \/>\n<meta property=\"og:site_name\" content=\"Matris\" \/>\n<meta property=\"og:image\" content=\"https:\/\/matris.eu\/wp-content\/uploads\/2024\/02\/matris_seo_image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/category\\\/noticias\\\/\",\"url\":\"https:\\\/\\\/matris.eu\\\/es\\\/category\\\/noticias\\\/\",\"name\":\"Noticias Archives | Matris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/category\\\/noticias\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/category\\\/noticias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/matris.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/matris.eu\\\/es\\\/\",\"name\":\"Servisni center Matris\",\"description\":\"Servis elektro, servo in vretenskih motorjev\",\"publisher\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#organization\"},\"alternateName\":\"Matris\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/matris.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#organization\",\"name\":\"Centro de servicio Matris\",\"alternateName\":\"Matris\",\"url\":\"https:\\\/\\\/matris.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Centro de servicio Matris\"},\"image\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Matrisdoo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/matris_doo\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noticias Archives | Matris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/matris.eu\/es\/category\/noticias\/","og_locale":"es_ES","og_type":"article","og_title":"Noticias Archives | Matris","og_url":"https:\/\/matris.eu\/es\/category\/noticias\/","og_site_name":"Matris","og_image":[{"width":1200,"height":1000,"url":"https:\/\/matris.eu\/wp-content\/uploads\/2024\/02\/matris_seo_image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/matris.eu\/es\/category\/noticias\/","url":"https:\/\/matris.eu\/es\/category\/noticias\/","name":"Noticias Archives | Matris","isPartOf":{"@id":"https:\/\/matris.eu\/es\/#website"},"breadcrumb":{"@id":"https:\/\/matris.eu\/es\/category\/noticias\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/matris.eu\/es\/category\/noticias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/matris.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Noticias"}]},{"@type":"WebSite","@id":"https:\/\/matris.eu\/es\/#website","url":"https:\/\/matris.eu\/es\/","name":"Servisni center Matris","description":"Servis elektro, servo in vretenskih motorjev","publisher":{"@id":"https:\/\/matris.eu\/es\/#organization"},"alternateName":"Matris","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/matris.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/matris.eu\/es\/#organization","name":"Centro de servicio Matris","alternateName":"Matris","url":"https:\/\/matris.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/matris.eu\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Centro de servicio Matris"},"image":{"@id":"https:\/\/matris.eu\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Matrisdoo","https:\/\/www.linkedin.com\/company\/matris_doo\/"]}]}},"_links":{"self":[{"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/categories\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/matris.eu\/es\/wp-json\/wp\/v2\/posts?categories=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}