{"id":4798,"date":"2026-04-07T11:21:29","date_gmt":"2026-04-07T09:21:29","guid":{"rendered":"https:\/\/matris.eu\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/"},"modified":"2026-04-08T11:12:52","modified_gmt":"2026-04-08T09:12:52","slug":"ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt","status":"publish","type":"post","link":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/","title":{"rendered":"\u00dcberholung von zwei Schneckengetrieben aus einer OEM-Anlage \u2013 wenn es keine Standardl\u00f6sung gibt"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8220;1\/1&#8243;][vc_column_text uncode_shortcode_id=&#8220;144960&#8243;]<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><img decoding=\"async\" class=\"aligncenter wp-image-4780 size-large\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h16_07-1024x694.png\" alt=\"\" width=\"840\" height=\"569\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h16_07-1024x694.png 1024w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h16_07-300x203.png 300w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h16_07-768x521.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h16_07-1536x1041.png 1536w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h16_07-350x237.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h16_07.png 1623w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Manche Anlagen sind schlicht zu kritisch, um sich einen Stillstand leisten zu k\u00f6nnen. Als uns der Kunde zwei Schneckengetriebe aus einer OEM-Anlage anvertraute, die nicht mehr erh\u00e4ltlich ist, war die Herausforderung klar: Original-Ersatzteile gibt es nicht, und eine neue Anlage w\u00fcrde potenziell mindestens <strong>6 Monate Wartezeit und Kosten von \u00fcber 100.000 \u20ac<\/strong> bedeuten. <\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Wir haben das anders gel\u00f6st.<\/p>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">Diagnose: starker Verschlei\u00df an Zahnr\u00e4dern und Wellen<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Nach der Pr\u00fcfung beider Getriebe stellten wir fest, dass die Zahnr\u00e4der und Schneckenwellen stark verschlissen sind. Leider waren die Getriebe seit vielen Jahren nicht regelm\u00e4\u00dfig gewartet worden, was die Herausforderung zus\u00e4tzlich versch\u00e4rfte. Da es sich um eine Anlage au\u00dferhalb der Serienproduktion handelt, konnten beim Lieferanten keine Ersatzteile bestellt werden.  <\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4785\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h24_46-1024x923.png\" alt=\"\" width=\"667\" height=\"601\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h24_46-1024x923.png 1024w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h24_46-300x270.png 300w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h24_46-768x692.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h24_46-350x316.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h24_46.png 1258w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>  <img decoding=\"async\" class=\"alignnone wp-image-4782\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h09_43-731x1024.png\" alt=\"\" width=\"430\" height=\"602\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h09_43-731x1024.png 731w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h09_43-214x300.png 214w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h09_43-768x1076.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h09_43-350x490.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h09_43.png 793w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/p>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">Herausforderung: nicht standardisierte Abmessungen<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Die gr\u00f6\u00dfere Abmessung der Zahnr\u00e4der erschwerte die Situation zus\u00e4tzlich \u2013 <strong>eine Standardfertigung auf spezialisierten Zahnradmaschinen war nicht m\u00f6glich<\/strong>. Wir brauchten einen anderen Ansatz. <\/p>\n<h3 class=\"text-text-100 mt-2 -mb-1 text-base font-bold\">Unsere L\u00f6sung:<\/h3>\n<ol class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-decimal flex flex-col gap-1 pl-8 mb-3\">\n<li class=\"whitespace-normal break-words pl-2\"><strong>3D-Konstruktion<\/strong> \u2013 Auf Basis der Vermessung der vorhandenen (verschlissenen) Teile erstellten wir ein pr\u00e4zises 3D-Modell der neuen Zahnr\u00e4der und Schneckenwellen.<\/li>\n<li class=\"whitespace-normal break-words pl-2\"><strong>5-Achs-CNC-Fr\u00e4sen in-house<\/strong> \u2013 Wir fr\u00e4sten die Teile in unserer eigenen Werkstatt auf einer 5-Achs-DMG Mori DMU 50 CNC-Fr\u00e4smaschine, was uns volle Kontrolle \u00fcber Qualit\u00e4t und Ma\u00dfgenauigkeit erm\u00f6glichte.<\/li>\n<li class=\"whitespace-normal break-words pl-2\"><strong>Komplett neue Zahnr\u00e4der und Schneckenwelle<\/strong> \u2013 Das Ergebnis sind Teile, die eine gleiche oder bessere langfristige Zuverl\u00e4ssigkeit als das Original gew\u00e4hrleisten.<\/li>\n<\/ol>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4788\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_41.png\" alt=\"\" width=\"650\" height=\"403\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_41.png 896w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_41-300x186.png 300w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_41-768x477.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_41-350x217.png 350w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>.  <img decoding=\"async\" class=\"alignnone wp-image-4786\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h30_30-1024x572.png\" alt=\"\" width=\"722\" height=\"403\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h30_30-1024x572.png 1024w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h30_30-300x167.png 300w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h30_30-768x429.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h30_30-350x195.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h30_30.png 1406w\" sizes=\"(max-width: 722px) 100vw, 722px\" \/><img decoding=\"async\" class=\"size-large wp-image-4789 alignnone\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_52-1-1024x502.png\" alt=\"\" width=\"840\" height=\"412\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_52-1-1024x502.png 1024w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_52-1-300x147.png 300w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_52-1-768x376.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_52-1-350x171.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h29_52-1.png 1074w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/p>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">Umfassende \u00dcberholung \u2013 alles aus einer Hand<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Neben dem Fr\u00e4sen der neuen Teile f\u00fchrten wir auch alle Standardprozesse einer umfassenden \u00dcberholung durch.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>\u00d6lwechsel<\/strong> wird bei Schneckengetrieben oft vernachl\u00e4ssigt, ist aber entscheidend \u2013 altes, verunreinigtes \u00d6l beschleunigt den Verschlei\u00df und reduziert den Wirkungsgrad der Kraft\u00fcbertragung. Frisches \u00d6l mit der richtigen Viskosit\u00e4t sorgt f\u00fcr optimale Schmierung und W\u00e4rmeabfuhr. <\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Austausch von Lagern und Dichtungen<\/strong> ist bei jedem ernsthaften Eingriff zwingend erforderlich. Verschlissene Lager verursachen Vibrationen und eine ungenaue Wellenf\u00fchrung, abgenutzte Dichtungen f\u00fchren zu \u00d6lleckagen und zum Eindringen von Schmutz ins Geh\u00e4use \u2013 was schnell zu einem erneuten Ausfall f\u00fchrt. <\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Messung der Toleranzen der Lagersitze<\/strong> zeigt uns, ob die Sitze im Geh\u00e4use noch innerhalb der Herstellertoleranzen liegen. Ein zu lockerer oder zu enger Sitz f\u00fchrt auch beim neuen Lager zu einem vorzeitigen Ausfall \u2013 deshalb \u00fcberlassen wir Toleranzen nicht dem R\u00e4tselraten. Wo die Toleranzen nicht mehr passen, setzen wir den Lagersitz instand \u2013 so stellen wir sicher, dass das gesamte Getriebe nach der \u00dcberholung geometrisch stimmig ist und f\u00fcr einen langfristig st\u00f6rungsfreien Betrieb bereitsteht.  <\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Laserauftragschwei\u00dfen und Schleifen der Welle<\/strong> sind erforderlich, wenn die Welle an den Lager- oder Dichtsitzen verschlissen ist. Beim Laserauftragschwei\u00dfen tragen wir Material \u00e4u\u00dferst pr\u00e4zise auf \u2013 ohne thermische Verz\u00fcge, die beim klassischen Schwei\u00dfen h\u00e4ufig als Nebeneffekt auftreten. Anschlie\u00dfend wird auf das exakt vorgegebene Ma\u00df geschliffen.  <\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4784\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h10_01.png\" alt=\"\" width=\"526\" height=\"575\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h10_01.png 526w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h10_01-274x300.png 274w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h10_01-350x383.png 350w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>  <img decoding=\"async\" class=\"alignnone wp-image-4792\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h28_31.png\" alt=\"\" width=\"555\" height=\"574\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h28_31.png 843w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h28_31-290x300.png 290w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h28_31-768x794.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h28_31-350x362.png 350w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>  <img decoding=\"async\" class=\"alignnone wp-image-4791\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h26_31-823x1024.png\" alt=\"\" width=\"462\" height=\"574\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h26_31-823x1024.png 823w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h26_31-241x300.png 241w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h26_31-768x955.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h26_31-350x435.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h26_31.png 850w\" sizes=\"(max-width: 462px) 100vw, 462px\" \/><\/p>\n<p>Jedes Getriebe wurde nach Abschluss aller Arbeiten gepr\u00fcft und f\u00fcr die R\u00fcckkehr in den Betrieb vorbereitet.<\/p>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\"><img decoding=\"async\" class=\"alignnone wp-image-4793\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50-1024x718.png\" alt=\"\" width=\"736\" height=\"516\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50-1024x718.png 1024w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50-300x210.png 300w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50-768x538.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50-1536x1077.png 1536w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50-350x245.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50.png 1625w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/> <img decoding=\"async\" class=\"alignnone size-large wp-image-4794\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h55_27-1024x629.png\" alt=\"\" width=\"840\" height=\"516\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h55_27-1024x629.png 1024w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h55_27-300x184.png 300w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h55_27-768x472.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h55_27-350x215.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h55_27.png 1412w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/h2>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">Ergebnis: Zeit- und Kostenersparnis<\/h2>\n<div class=\"overflow-x-auto w-full px-2 mb-6\">In zwei Monaten und zu einem Zehntel der Kosten f\u00fcr den Kauf einer neuen Anlage erm\u00f6glichten wir dem Kunden die Fortsetzung der Produktion \u2013 ohne langen Stillstand und ohne unverh\u00e4ltnism\u00e4\u00dfige Kosten. Auf alle ausgef\u00fchrten Arbeiten gew\u00e4hren wir 12 Monate Garantie. <\/div>\n<div>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><em><img decoding=\"async\" class=\"alignnone size-large wp-image-4796\" src=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_11h18_39-1024x476.png\" alt=\"\" width=\"840\" height=\"390\" srcset=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_11h18_39-1024x476.png 1024w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_11h18_39-300x140.png 300w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_11h18_39-768x357.png 768w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_11h18_39-350x163.png 350w, https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_11h18_39.png 1264w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><\/em><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><em>Haben Sie eine \u00e4hnliche Herausforderung? Kontaktieren Sie uns \u2013 L\u00f6sungen f\u00fcr Sonderf\u00e4lle sind unsere Spezialisierung. <\/em><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f4e9.svg\" alt=\"\ud83d\udce9\"> <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"mailto:info@matris.eu\">info@matris.eu<\/a> | <img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f4de.svg\" alt=\"\ud83d\udcde\"> +386 4 29 26 900<\/strong><\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00dcberholung von zwei Schneckengetrieben aus einer OEM-Anlage, die nicht mehr erh\u00e4ltlich ist. Da keine originalen Ersatzteile verf\u00fcgbar sind, haben wir stark verschlissene Zahnr\u00e4der und Schneckenwellen komplett neu gefertigt \u2013 mit eigener 3D-Konstruktion und 5-Achs-CNC-Fr\u00e4sen. Zusammen mit der umfassenden Getriebe\u00fcberholung haben wir dem Kunden in zwei Monaten 6+ Monate potenziellen Stillstand und mehr als 100.000 \u20ac potenzielle Kosten erspart. Mit 12 Monaten Garantie.   <\/p>\n","protected":false},"author":6,"featured_media":4801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-4798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-der-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ma\u00dfgeschneiderte \u00dcberholung von Schneckengetrieben \u2013 wenn es keine Originalteile mehr gibt | Matris<\/title>\n<meta name=\"description\" content=\"Wir haben zwei Schneckengetriebe aus einer Anlage \u00fcberholt, die nicht mehr erh\u00e4ltlich ist. Neue Zahnr\u00e4der und Wellen, in-house gefertigt auf einer 5-Achs-CNC-Fr\u00e4smaschine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ma\u00dfgeschneiderte \u00dcberholung von Schneckengetrieben \u2013 wenn es keine Originalteile mehr gibt | Matris\" \/>\n<meta property=\"og:description\" content=\"Wir haben zwei Schneckengetriebe aus einer Anlage \u00fcberholt, die nicht mehr erh\u00e4ltlich ist. Neue Zahnr\u00e4der und Wellen, in-house gefertigt auf einer 5-Achs-CNC-Fr\u00e4smaschine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/\" \/>\n<meta property=\"og:site_name\" content=\"Matris\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Matrisdoo\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-07T09:21:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T09:12:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50-1024x718.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Matris Urednik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matris Urednik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/\"},\"author\":{\"name\":\"Matris Urednik\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#\\\/schema\\\/person\\\/524964cfd51b9607239e6a48511c16c8\"},\"headline\":\"\u00dcberholung von zwei Schneckengetrieben aus einer OEM-Anlage \u2013 wenn es keine Standardl\u00f6sung gibt\",\"datePublished\":\"2026-04-07T09:21:29+00:00\",\"dateModified\":\"2026-04-08T09:12:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/\"},\"wordCount\":581,\"publisher\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/matris.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2026-04-07_10h54_50.png\",\"articleSection\":[\"Der Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/\",\"url\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/\",\"name\":\"Ma\u00dfgeschneiderte \u00dcberholung von Schneckengetrieben \u2013 wenn es keine Originalteile mehr gibt | Matris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/matris.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2026-04-07_10h54_50.png\",\"datePublished\":\"2026-04-07T09:21:29+00:00\",\"dateModified\":\"2026-04-08T09:12:52+00:00\",\"description\":\"Wir haben zwei Schneckengetriebe aus einer Anlage \u00fcberholt, die nicht mehr erh\u00e4ltlich ist. Neue Zahnr\u00e4der und Wellen, in-house gefertigt auf einer 5-Achs-CNC-Fr\u00e4smaschine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/matris.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2026-04-07_10h54_50.png\",\"contentUrl\":\"https:\\\/\\\/matris.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2026-04-07_10h54_50.png\",\"width\":1625,\"height\":1139},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/matris.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcberholung von zwei Schneckengetrieben aus einer OEM-Anlage \u2013 wenn es keine Standardl\u00f6sung gibt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/matris.eu\\\/de\\\/\",\"name\":\"Servisni center Matris\",\"description\":\"Servis elektro, servo in vretenskih motorjev\",\"publisher\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#organization\"},\"alternateName\":\"Matris\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/matris.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#organization\",\"name\":\"Servicezentrum Matris\",\"alternateName\":\"Matris\",\"url\":\"https:\\\/\\\/matris.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Servicezentrum Matris\"},\"image\":{\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Matrisdoo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/matris_doo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/matris.eu\\\/de\\\/#\\\/schema\\\/person\\\/524964cfd51b9607239e6a48511c16c8\",\"name\":\"Matris Urednik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77935bb9ad657464aa79a5465347d7f1348916474726cf560c38e7968985c854?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77935bb9ad657464aa79a5465347d7f1348916474726cf560c38e7968985c854?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77935bb9ad657464aa79a5465347d7f1348916474726cf560c38e7968985c854?s=96&d=mm&r=g\",\"caption\":\"Matris Urednik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ma\u00dfgeschneiderte \u00dcberholung von Schneckengetrieben \u2013 wenn es keine Originalteile mehr gibt | Matris","description":"Wir haben zwei Schneckengetriebe aus einer Anlage \u00fcberholt, die nicht mehr erh\u00e4ltlich ist. Neue Zahnr\u00e4der und Wellen, in-house gefertigt auf einer 5-Achs-CNC-Fr\u00e4smaschine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/","og_locale":"de_DE","og_type":"article","og_title":"Ma\u00dfgeschneiderte \u00dcberholung von Schneckengetrieben \u2013 wenn es keine Originalteile mehr gibt | Matris","og_description":"Wir haben zwei Schneckengetriebe aus einer Anlage \u00fcberholt, die nicht mehr erh\u00e4ltlich ist. Neue Zahnr\u00e4der und Wellen, in-house gefertigt auf einer 5-Achs-CNC-Fr\u00e4smaschine.","og_url":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/","og_site_name":"Matris","article_publisher":"https:\/\/www.facebook.com\/Matrisdoo","article_published_time":"2026-04-07T09:21:29+00:00","article_modified_time":"2026-04-08T09:12:52+00:00","og_image":[{"width":1024,"height":718,"url":"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50-1024x718.png","type":"image\/png"}],"author":"Matris Urednik","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Matris Urednik","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/#article","isPartOf":{"@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/"},"author":{"name":"Matris Urednik","@id":"https:\/\/matris.eu\/de\/#\/schema\/person\/524964cfd51b9607239e6a48511c16c8"},"headline":"\u00dcberholung von zwei Schneckengetrieben aus einer OEM-Anlage \u2013 wenn es keine Standardl\u00f6sung gibt","datePublished":"2026-04-07T09:21:29+00:00","dateModified":"2026-04-08T09:12:52+00:00","mainEntityOfPage":{"@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/"},"wordCount":581,"publisher":{"@id":"https:\/\/matris.eu\/de\/#organization"},"image":{"@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/#primaryimage"},"thumbnailUrl":"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50.png","articleSection":["Der Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/","url":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/","name":"Ma\u00dfgeschneiderte \u00dcberholung von Schneckengetrieben \u2013 wenn es keine Originalteile mehr gibt | Matris","isPartOf":{"@id":"https:\/\/matris.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/#primaryimage"},"image":{"@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/#primaryimage"},"thumbnailUrl":"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50.png","datePublished":"2026-04-07T09:21:29+00:00","dateModified":"2026-04-08T09:12:52+00:00","description":"Wir haben zwei Schneckengetriebe aus einer Anlage \u00fcberholt, die nicht mehr erh\u00e4ltlich ist. Neue Zahnr\u00e4der und Wellen, in-house gefertigt auf einer 5-Achs-CNC-Fr\u00e4smaschine.","breadcrumb":{"@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/#primaryimage","url":"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50.png","contentUrl":"https:\/\/matris.eu\/wp-content\/uploads\/2026\/04\/2026-04-07_10h54_50.png","width":1625,"height":1139},{"@type":"BreadcrumbList","@id":"https:\/\/matris.eu\/de\/ueberholung-von-zwei-schneckengetrieben-aus-einer-oem-anlage-wenn-es-keine-standardloesung-gibt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/matris.eu\/de\/"},{"@type":"ListItem","position":2,"name":"\u00dcberholung von zwei Schneckengetrieben aus einer OEM-Anlage \u2013 wenn es keine Standardl\u00f6sung gibt"}]},{"@type":"WebSite","@id":"https:\/\/matris.eu\/de\/#website","url":"https:\/\/matris.eu\/de\/","name":"Servisni center Matris","description":"Servis elektro, servo in vretenskih motorjev","publisher":{"@id":"https:\/\/matris.eu\/de\/#organization"},"alternateName":"Matris","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/matris.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/matris.eu\/de\/#organization","name":"Servicezentrum Matris","alternateName":"Matris","url":"https:\/\/matris.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/matris.eu\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Servicezentrum Matris"},"image":{"@id":"https:\/\/matris.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Matrisdoo","https:\/\/www.linkedin.com\/company\/matris_doo\/"]},{"@type":"Person","@id":"https:\/\/matris.eu\/de\/#\/schema\/person\/524964cfd51b9607239e6a48511c16c8","name":"Matris Urednik","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/77935bb9ad657464aa79a5465347d7f1348916474726cf560c38e7968985c854?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/77935bb9ad657464aa79a5465347d7f1348916474726cf560c38e7968985c854?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/77935bb9ad657464aa79a5465347d7f1348916474726cf560c38e7968985c854?s=96&d=mm&r=g","caption":"Matris Urednik"}}]}},"_links":{"self":[{"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/posts\/4798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/comments?post=4798"}],"version-history":[{"count":8,"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/posts\/4798\/revisions"}],"predecessor-version":[{"id":4850,"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/posts\/4798\/revisions\/4850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/media\/4801"}],"wp:attachment":[{"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/media?parent=4798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/categories?post=4798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/matris.eu\/de\/wp-json\/wp\/v2\/tags?post=4798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}